{"id":4122,"date":"2020-04-02T10:45:15","date_gmt":"2020-04-02T10:45:15","guid":{"rendered":"https:\/\/www.leafieldmarine.com\/politica-de-privacidad\/"},"modified":"2020-04-02T10:45:15","modified_gmt":"2020-04-02T10:45:15","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"<h4>Qui\u00e9nes somos<\/h4>\n<p>Leafield Marine Limited (&#8216;nosotros&#8217; o &#8216;nos&#8217;) es una empresa privada registrada y que opera en el Reino Unido.&nbsp;El n\u00famero de registro de la compa\u00f1\u00eda es 05870564 y el domicilio social es 9 Atworth Business Park, Bath Rd, Atworth, Melksham, Wiltshire, SN12 8SB, Reino Unido. &nbsp;Nos comprometemos a recopilar solo los datos personales que necesitamos para llevar a cabo nuestro negocio y a garantizar que los mantenemos seguros.<\/p>\n<h4>A qui\u00e9n se aplica la pol\u00edtica<\/h4>\n<p>Esta pol\u00edtica se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial. Tambi\u00e9n se aplica a los empleados existentes y anteriores o a cualquier persona que nos proporcione datos personales como posible empleado (consulte la secci\u00f3n separada a continuaci\u00f3n).<\/p>\n<h4>Lo que recopilamos<\/h4>\n<p>Recopilamos informaci\u00f3n sobre usted cuando nos proporciona voluntariamente informaci\u00f3n a trav\u00e9s de nuestro formulario de solicitud de consulta y cotizaci\u00f3n en nuestro sitio web o cuando nos proporciona voluntariamente una direcci\u00f3n de correo electr\u00f3nico u otra informaci\u00f3n de contacto.<\/p>\n<h4>C\u00f3mo usamos la informaci\u00f3n<\/h4>\n<p>Utilizamos la informaci\u00f3n que nos proporciona para realizar negocios con usted o su empresa. Esto puede incluir proporcionar cotizaciones, muestras o procesar transacciones de ventas y compras. No proporcionamos sus datos a procesadores externos a menos que tengamos una base legal para hacerlo.<\/p>\n<h4>Galletas<\/h4>\n<p>Una cookie es un peque\u00f1o archivo de texto que se puede colocar en su dispositivo cuando visita nuestro sitio y completa un formulario de consulta. Esto guarda sus datos localmente en caso de que vuelva a enviar el formulario, pero es opcional.<\/p>\n<h4>Recopilaci\u00f3n de datos y prop\u00f3sito<\/h4>\n<p>Recopilamos datos que puede ofrecer voluntariamente mientras realiza consultas o realiza negocios con nosotros. El env\u00edo verbal, por correo electr\u00f3nico u otro env\u00edo electr\u00f3nico de una consulta, una solicitud de cotizaci\u00f3n, una orden de compra o una orden de venta proporcionan una base legal para que procesemos sus datos.<\/p>\n<h4>Almacenamiento de datos<\/h4>\n<p>Almacenamos los datos durante el tiempo que necesitemos para el prop\u00f3sito que se proporcion\u00f3. Almacenamos datos de forma segura dentro del Reino Unido y la UE. &nbsp;Hemos implementado pol\u00edticas de TI para garantizar que mantenemos un est\u00e1ndar de seguridad efectivo y estamos acreditados por Cyber Essentials.<\/p>\n<p>Nuestras normas, pol\u00edticas y medidas t\u00e9cnicas de seguridad est\u00e1n dise\u00f1adas para proteger los datos personales del acceso no autorizado, el uso o la divulgaci\u00f3n indebidos, la modificaci\u00f3n no autorizada, la destrucci\u00f3n ilegal o la p\u00e9rdida accidental y el procesamiento ilegal.<\/p>\n<h4>Acceso a los datos que podemos tener<\/h4>\n<p>Puede preguntarnos si conservamos sus datos personales enviando un correo electr\u00f3nico a:<span>&nbsp;<\/span><a href=\"mailto:datacontroller@leafieldmarine.co.uk\">datacontroller@leafieldmarine.co.uk<\/a><span>&nbsp;<\/span>o escribiendo al Controlador de datos a la direcci\u00f3n registrada que se muestra arriba.<\/p>\n<p>Le proporcionaremos una copia legible de los datos personales que conservamos sobre usted, en el plazo de un mes a partir de la recepci\u00f3n de esta solicitud, aunque requeriremos una prueba de su identidad. Proporcionaremos esta informaci\u00f3n de forma gratuita.<\/p>\n<p>Sin embargo, cobraremos una tarifa razonable cuando una solicitud de informaci\u00f3n sea manifiestamente infundada o excesiva, especialmente si es repetitiva.&nbsp; Cualquier tarifa se basar\u00e1 en el costo administrativo para proporcionar la informaci\u00f3n.&nbsp; Podemos rechazar una solicitud si creemos que es excesiva, indirecta o inapropiada y usted tiene el derecho de impugnar esa decisi\u00f3n presentando una queja ante la autoridad supervisora correspondiente.<\/p>\n<p>Le permitimos impugnar los datos que tenemos sobre usted y, cuando corresponda, es posible que los datos se borren, rectifiquen o modifiquen si son incorrectos o inexactos.<\/p>\n<h4>Borrado de datos<\/h4>\n<p>Tiene derecho a que se borren sus datos personales para evitar el procesamiento en las siguientes circunstancias espec\u00edficas:<\/p>\n<ul>\n<li>Cuando los datos personales ya no sean necesarios en relaci\u00f3n con los fines para los que se recopilaron \/ procesaron originalmente.<\/li>\n<li>Si desea retirar su consentimiento.<\/li>\n<li>Si se opone al procesamiento y no existe un inter\u00e9s leg\u00edtimo primordial para continuar con el procesamiento.<\/li>\n<li>Los datos se procesaron ilegalmente de acuerdo con el GDPR.<\/li>\n<li>Los datos personales deben borrarse para cumplir con una obligaci\u00f3n legal.<\/li>\n<\/ul>\n<h4>Enlaces a otros sitios web<\/h4>\n<p>Nuestro sitio web puede contener enlaces para permitirle visitar otros sitios web.&nbsp; Una vez que haya utilizado estos enlaces para abandonar nuestro sitio web, debe tener en cuenta que no tenemos control sobre ning\u00fan otro sitio web. Por lo tanto, no podemos ser responsables de los datos que proporcione a estos sitios web que no se rigen por esta pol\u00edtica de privacidad.&nbsp; Debe tener cuidado y consultar la pol\u00edtica de privacidad del sitio web en cuesti\u00f3n.<\/p>\n<h4>Solicitantes de empleo, empleados actuales y anteriores<\/h4>\n<p>Los empleados ser\u00e1n informados de los datos que tenemos a trav\u00e9s de sus t\u00e9rminos y condiciones de empleo.&nbsp; Solo conservaremos los datos relacionados con los ex empleados durante el tiempo que sea necesario, nuevamente esto se establece en el contrato de trabajo.<\/p>\n<p>Si est\u00e1 haciendo una solicitud para unirse a nosotros como empleado. Le pediremos y solo procesaremos datos relevantes para su solicitud de empleo. Sus datos se mantendr\u00e1n de forma segura y no se transmitir\u00e1n a terceros sin su consentimiento.<\/p>\n<p>Utilizaremos sus datos de contacto personales para avanzar en su solicitud y cualquier otro dato para evaluar su idoneidad y, si es necesario, para completar las verificaciones previas al empleo, incluida la verificaci\u00f3n de su identidad y su derecho a trabajar dentro del Reino Unido.&nbsp; Por lo tanto, podemos solicitarle una prueba de identidad, una prueba de calificaciones y detalles de cualquier \u00e1rbitro requerido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui\u00e9nes somos Leafield Marine Limited (&#8216;nosotros&#8217; o &#8216;nos&#8217;) es una empresa privada registrada y que opera en el Reino Unido.&nbsp;El n\u00famero de registro de la compa\u00f1\u00eda es 05870564 y el domicilio social es 9 Atworth Business Park, Bath Rd, Atworth, Melksham, Wiltshire, SN12 8SB, Reino Unido. &nbsp;Nos comprometemos a recopilar solo los datos personales que &hellip;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"content-type":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":["page","type-page","entry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidad - Leafield Marine<\/title>\n<meta name=\"description\" content=\"La pol\u00edtica de privacidad de Leafield Marine se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad - Leafield Marine\" \/>\n<meta property=\"og:description\" content=\"La pol\u00edtica de privacidad de Leafield Marine se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Leafield Marine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/politica-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/politica-de-privacidad\\\/\",\"name\":\"Pol\u00edtica de Privacidad - Leafield Marine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/#website\"},\"datePublished\":\"2020-04-02T10:45:15+00:00\",\"description\":\"La pol\u00edtica de privacidad de Leafield Marine se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/politica-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/politica-de-privacidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/politica-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/\",\"name\":\"Leafield Marine\",\"description\":\"World Class Air Valves for Inflatable Structures\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/#organization\",\"name\":\"Leafield Marine\",\"url\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.leafieldmarine.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/leafield-marine-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.leafieldmarine.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/leafield-marine-logo.png\",\"width\":247,\"height\":191,\"caption\":\"Leafield Marine\"},\"image\":{\"@id\":\"https:\\\/\\\/www.leafieldmarine.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad - Leafield Marine","description":"La pol\u00edtica de privacidad de Leafield Marine se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Privacidad - Leafield Marine","og_description":"La pol\u00edtica de privacidad de Leafield Marine se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial.","og_url":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/","og_site_name":"Leafield Marine","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/","url":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de Privacidad - Leafield Marine","isPartOf":{"@id":"https:\/\/www.leafieldmarine.com\/es\/#website"},"datePublished":"2020-04-02T10:45:15+00:00","description":"La pol\u00edtica de privacidad de Leafield Marine se aplica a clientes, proveedores y cualquier persona que visite nuestro sitio web como cliente potencial.","breadcrumb":{"@id":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leafieldmarine.com\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leafieldmarine.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/www.leafieldmarine.com\/es\/#website","url":"https:\/\/www.leafieldmarine.com\/es\/","name":"Leafield Marine","description":"World Class Air Valves for Inflatable Structures","publisher":{"@id":"https:\/\/www.leafieldmarine.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leafieldmarine.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.leafieldmarine.com\/es\/#organization","name":"Leafield Marine","url":"https:\/\/www.leafieldmarine.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.leafieldmarine.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.leafieldmarine.com\/wp-content\/uploads\/2022\/10\/leafield-marine-logo.png","contentUrl":"https:\/\/www.leafieldmarine.com\/wp-content\/uploads\/2022\/10\/leafield-marine-logo.png","width":247,"height":191,"caption":"Leafield Marine"},"image":{"@id":"https:\/\/www.leafieldmarine.com\/es\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/pages\/4122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/comments?post=4122"}],"version-history":[{"count":0,"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/pages\/4122\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.leafieldmarine.com\/es\/wp-json\/wp\/v2\/media?parent=4122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}